{"id":23120,"date":"2024-05-09T15:47:52","date_gmt":"2024-05-09T13:47:52","guid":{"rendered":"https:\/\/smartfense.com\/evento\/funciona-realmente-tu-plan-de-concienciacion-en-ciberseguridad-en-tu-organizacion\/"},"modified":"2024-06-01T11:59:51","modified_gmt":"2024-06-01T09:59:51","slug":"il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo","status":"publish","type":"tribe_events","link":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/","title":{"rendered":"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo]"},"content":{"rendered":"<p>Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero?<\/p>\n<p>Esistono obblighi di formazione e sensibilizzazione sulla cybersecurity?<\/p>\n<p>Quanto sono utili i pacchetti di sensibilizzazione generici?<\/p>\n<p>Come si misura l\u2019efficacia di un piano di sensibilizzazione sulla cybersecurity?<\/p>\n<p>Vi invitiamo a partecipare al nostro webinar il 6 giugno alle ore 12.00.<\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/attendee.gotowebinar.com\/register\/310762007468963678\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/attendee.gotowebinar.com\/register\/310762007468963678&source=gmail&ust=1715337203825000&usg=AOvVaw0m5KH7-y8L_oMT7ZK_OeC_\">https:\/\/attendee.gotowebinar.com\/register\/310762007468963678<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero? Esistono obblighi di formazione e sensibilizzazione sulla cybersecurity? Quanto sono utili i pacchetti di sensibilizzazione generici? Come si [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":22583,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"yes","_tribe_events_virtual_video_source":"video","_tribe_events_virtual_embed_video":"yes","_tribe_events_virtual_linked_button_text":"Watch","_tribe_events_virtual_linked_button":"yes","_tribe_events_virtual_show_embed_at":"immediately","_tribe_events_virtual_show_embed_to":["all"],"_tribe_events_virtual_show_on_event":"yes","_tribe_events_virtual_show_on_views":"yes","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[828],"class_list":["post-23120","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-webinar-online-it","cat_webinar-online-it","tribe-events-virtual-event"],"acf":[],"yoast_head":" \n<title>Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo] - SMARTFENSE<\/title>\n<meta name=\"description\" content=\"Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero? Esistono obblighi di formazione e\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo] - SMARTFENSE\" \/>\n<meta property=\"og:description\" content=\"Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero? Esistono obblighi di formazione e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/\" \/>\n<meta property=\"og:site_name\" content=\"SMARTFENSE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-01T09:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartfense.com\/file\/2024\/05\/savethedate.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/\",\"name\":\"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo] - SMARTFENSE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/savethedate.jpg\",\"datePublished\":\"2024-05-09T13:47:52+00:00\",\"dateModified\":\"2024-06-01T09:59:51+00:00\",\"description\":\"Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero? Esistono obblighi di formazione e\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/savethedate.jpg\",\"contentUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/savethedate.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/evento\\\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/smartfense.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/smartfense.com\\\/it\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/smartfense.com\\\/it\\\/\",\"name\":\"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartfense.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/#organization\",\"name\":\"SMARTFENSE\",\"url\":\"https:\\\/\\\/smartfense.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"contentUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"width\":241,\"height\":40,\"caption\":\"SMARTFENSE\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n ","yoast_head_json":{"title":"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo] - SMARTFENSE","description":"Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero? Esistono obblighi di formazione e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/","og_locale":"it_IT","og_type":"article","og_title":"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo] - SMARTFENSE","og_description":"Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero? Esistono obblighi di formazione e","og_url":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/","og_site_name":"SMARTFENSE","article_modified_time":"2024-06-01T09:59:51+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/smartfense.com\/file\/2024\/05\/savethedate.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/","url":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/","name":"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo] - SMARTFENSE","isPartOf":{"@id":"https:\/\/smartfense.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/#primaryimage"},"image":{"@id":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/#primaryimage"},"thumbnailUrl":"https:\/\/smartfense.com\/file\/2024\/05\/savethedate.jpg","datePublished":"2024-05-09T13:47:52+00:00","dateModified":"2024-06-01T09:59:51+00:00","description":"Il piano di sensibilizzazione sulla sicurezza informatica della vostra organizzazione funziona davvero? Esistono obblighi di formazione e","breadcrumb":{"@id":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/#primaryimage","url":"https:\/\/smartfense.com\/file\/2024\/05\/savethedate.jpg","contentUrl":"https:\/\/smartfense.com\/file\/2024\/05\/savethedate.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/smartfense.com\/it\/evento\/il-piano-di-awareness-sulla-sicurezza-informatica-della-vostra-organizzazione-funziona-davvero-in-spagnolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/smartfense.com\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/smartfense.com\/it\/eventos\/"},{"@type":"ListItem","position":3,"name":"Il piano di awareness sulla sicurezza informatica della vostra organizzazione funziona davvero? [in spagnolo]"}]},{"@type":"WebSite","@id":"https:\/\/smartfense.com\/it\/#website","url":"https:\/\/smartfense.com\/it\/","name":"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad","description":"","publisher":{"@id":"https:\/\/smartfense.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartfense.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/smartfense.com\/it\/#organization","name":"SMARTFENSE","url":"https:\/\/smartfense.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/smartfense.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","contentUrl":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","width":241,"height":40,"caption":"SMARTFENSE"},"image":{"@id":"https:\/\/smartfense.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/tribe_events\/23120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/comments?post=23120"}],"version-history":[{"count":1,"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/tribe_events\/23120\/revisions"}],"predecessor-version":[{"id":23125,"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/tribe_events\/23120\/revisions\/23125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/media\/22583"}],"wp:attachment":[{"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/media?parent=23120"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/tags?post=23120"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/smartfense.com\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=23120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}