{"id":216,"count":7,"description":"","link":"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/","name":"gamification","slug":"gamification-es-ar","taxonomy":"post_tag","meta":[],"yoast_head":" \n<title>gamification - tag - SMARTFENSE<\/title>\n<meta name=\"description\" content=\"Todos los art\u00edculos de nuestro blog relacionados con &#039; gamification &#039;. Actualizado en el \u00e1mbito de la ciber seguridad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gamification - tag - SMARTFENSE\" \/>\n<meta property=\"og:description\" content=\"Todos los art\u00edculos de nuestro blog relacionados con &#039; gamification &#039;. Actualizado en el \u00e1mbito de la ciber seguridad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/\" \/>\n<meta property=\"og:site_name\" content=\"SMARTFENSE\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartfense.com\/file\/2023\/11\/smretfense-cybersecurity-awareness-es.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1038\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/tag\\\/gamification-es-ar\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/tag\\\/gamification-es-ar\\\/\",\"name\":\"gamification - tag - SMARTFENSE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#website\"},\"description\":\"Todos los art\u00edculos de nuestro blog relacionados con ' gamification '. Actualizado en el \u00e1mbito de la ciber seguridad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/tag\\\/gamification-es-ar\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/tag\\\/gamification-es-ar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/concientizacion-en-ciberseguridad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"gamification\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#website\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/\",\"name\":\"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\",\"name\":\"SMARTFENSE\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"contentUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"width\":241,\"height\":40,\"caption\":\"SMARTFENSE\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n ","yoast_head_json":{"title":"gamification - tag - SMARTFENSE","description":"Todos los art\u00edculos de nuestro blog relacionados con ' gamification '. Actualizado en el \u00e1mbito de la ciber seguridad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/","og_locale":"es_ES","og_type":"article","og_title":"gamification - tag - SMARTFENSE","og_description":"Todos los art\u00edculos de nuestro blog relacionados con ' gamification '. Actualizado en el \u00e1mbito de la ciber seguridad.","og_url":"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/","og_site_name":"SMARTFENSE","og_image":[{"width":1920,"height":1038,"url":"https:\/\/smartfense.com\/file\/2023\/11\/smretfense-cybersecurity-awareness-es.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/","url":"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/","name":"gamification - tag - SMARTFENSE","isPartOf":{"@id":"https:\/\/smartfense.com\/es-ar\/#website"},"description":"Todos los art\u00edculos de nuestro blog relacionados con ' gamification '. Actualizado en el \u00e1mbito de la ciber seguridad.","breadcrumb":{"@id":"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/#breadcrumb"},"inLanguage":"es-AR"},{"@type":"BreadcrumbList","@id":"https:\/\/smartfense.com\/es-ar\/tag\/gamification-es-ar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/smartfense.com\/es-ar\/concientizacion-en-ciberseguridad\/"},{"@type":"ListItem","position":2,"name":"gamification"}]},{"@type":"WebSite","@id":"https:\/\/smartfense.com\/es-ar\/#website","url":"https:\/\/smartfense.com\/es-ar\/","name":"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad","description":"","publisher":{"@id":"https:\/\/smartfense.com\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartfense.com\/es-ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/smartfense.com\/es-ar\/#organization","name":"SMARTFENSE","url":"https:\/\/smartfense.com\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","contentUrl":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","width":241,"height":40,"caption":"SMARTFENSE"},"image":{"@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/tags\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts?tags=216"},{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/tribe_events?tags=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}