{"id":38556,"date":"2025-08-22T12:05:19","date_gmt":"2025-08-22T10:05:19","guid":{"rendered":"https:\/\/smartfense.com\/sin-categorizar\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/"},"modified":"2025-08-26T11:36:27","modified_gmt":"2025-08-26T09:36:27","slug":"cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad","status":"publish","type":"post","link":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/","title":{"rendered":"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones, independientemente del sector al que pertenezcan, est\u00e1n expuestas a exigencias crecientes en torno a la protecci\u00f3n de la informaci\u00f3n, la privacidad de los datos personales y la gesti\u00f3n de incidentes de seguridad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cumplir con estas normativas, adem\u00e1s de evitar sanciones, tambi\u00e9n demuestra <\/span><b>compromiso, fortalece la confianza de clientes y socios<\/b><span style=\"font-weight: 400;\">, y contribuye a construir una cultura organizacional responsable frente a los riesgos digitales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es en ese marco donde nuestra plataforma tiene un rol estrat\u00e9gico: ofrece <\/span><b>contenidos de concientizaci\u00f3n <\/b><span style=\"font-weight: 400;\">que est\u00e1n directamente <\/span><b>alineados con normativas internacionales<\/b><span style=\"font-weight: 400;\">. Esto permite a las organizaciones <\/span><b>concientizar a sus equipos y<\/b><span style=\"font-weight: 400;\">, al mismo tiempo,<\/span><b> generar evidencia concreta de cumplimiento<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-38479\" src=\"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-11.jpg\" alt=\"balanza\" width=\"1920\" height=\"960\" srcset=\"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-11.jpg 1920w, https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-11-300x150.jpg 300w, https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-11-1024x512.jpg 1024w, https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-11-768x384.jpg 768w, https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-11-1536x768.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<h3><b>Los pilares principales del cumplimiento<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A continuaci\u00f3n, un repaso por las m\u00e1s relevantes:<\/span><\/p>\n<h4><b>GDPR: proteger la privacidad de los datos personales<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">El Reglamento General de Protecci\u00f3n de Datos de la UE (GDPR) es aplicable a todas las organizaciones que<\/span><b> traten datos personales<\/b><span style=\"font-weight: 400;\"> de ciudadanos europeos, sin importar d\u00f3nde est\u00e9n ubicadas.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">En SMARTFENSE, abordamos el GDPR desde dos frentes:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Contenidos para <\/span><b>usuarios en general<\/b><span style=\"font-weight: 400;\">: principios del tratamiento, consentimiento, derechos del individuo, protecci\u00f3n de datos de menores, y m\u00e1s.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Contenidos para <\/span><b>encargados y responsables del tratamiento<\/b><span style=\"font-weight: 400;\">: privacidad por dise\u00f1o y por defecto, contrataci\u00f3n de proveedores, seguridad en las transferencias internacionales y notificaci\u00f3n de brechas.<\/span><\/li>\n<\/ul>\n<h4><b>HIPAA: asegurar el tratamiento de la informaci\u00f3n m\u00e9dica<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">La Ley de Portabilidad y Responsabilidad del Seguro M\u00e9dico de EE.UU (HIPAA) <\/span><b>regula el tratamiento de informaci\u00f3n m\u00e9dica protegida<\/b><span style=\"font-weight: 400;\"> (PHI) en organizaciones de salud y\u00a0 proveedores de tecnolog\u00eda m\u00e9dica.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Los contenidos disponibles en nuestra plataforma permiten comprender:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Qu\u00e9 es la informaci\u00f3n m\u00e9dica protegida (PHI y ePHI) y c\u00f3mo se debe proteger.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Qu\u00e9 obligaciones tienen las entidades cubiertas y cu\u00e1les son las sanciones por incumplimiento.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Qu\u00e9 pr\u00e1cticas favorecen la confidencialidad, integridad y disponibilidad de la informaci\u00f3n de salud.<\/span><\/li>\n<\/ul>\n<h4><b>ISO\/IEC 27001 y 27002: construir una cultura de seguridad desde adentro<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Estos est\u00e1ndares internacionales proporcionan una gu\u00eda clara para establecer un <\/span><b>Sistema de Gesti\u00f3n de Seguridad de la Informaci\u00f3n (SGSI).<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">SMARTFENSE contribuye al cumplimiento de los requisitos vinculados con la concientizaci\u00f3n del personal ofreciendo contenidos que refuerzan el comportamiento seguro dentro de la organizaci\u00f3n.<\/span><\/p>\n<h4><b>NIS2: fortalecer la ciberseguridad en sectores cr\u00edticos<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">La <\/span><b>Directiva NIS2<\/b><span style=\"font-weight: 400;\"> (UE 2022\/2555) es la evoluci\u00f3n de la primera Directiva NIS (2016). Su objetivo principal es establecer un marco com\u00fan para<\/span><b> garantizar la seguridad de las redes y sistemas de informaci\u00f3n <\/b><span style=\"font-weight: 400;\">en sectores considerados cr\u00edticos, como energ\u00eda, transporte, salud, servicios financieros y digital.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nuestra plataforma facilita la concientizaci\u00f3n continua requerida por la directiva, especialmente en lo que respecta a gesti\u00f3n de incidentes, pr\u00e1cticas b\u00e1sicas de ciberhigiene, responsabilidades de la direcci\u00f3n, y reportes.<\/span><\/p>\n<h4><b>DORA: afianzar la resiliencia digital en el sector financiero<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">El Reglamento de Resiliencia Operativa Digital de la UE (DORA busca asegurar que <\/span><b>las entidades financieras puedan<\/b> <b>resistir, reaccionar y recuperarse<\/b><span style=\"font-weight: 400;\"> ante incidentes relacionados con tecnolog\u00edas de la informaci\u00f3n.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Nuestros contenidos se orientan a:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sensibilizar sobre riesgos TIC.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Promover buenas pr\u00e1cticas en resiliencia digital.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Asegurar la adecuada gesti\u00f3n y reporte de incidentes.<\/span><\/li>\n<\/ul>\n<h4><b>PCI DSS: proteger los datos de titulares de tarjetas<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">El Est\u00e1ndar de Seguridad de Datos para la Industria de Tarjetas de Pago (PCI DSS)<\/span> <span style=\"font-weight: 400;\">establece requisitos t\u00e9cnicos y organizativos para <\/span><b>proteger los datos de titulares de tarjetas<\/b><span style=\"font-weight: 400;\"> en entornos que procesan, almacenan o transmiten informaci\u00f3n de pagos.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">A trav\u00e9s de nuestros contenidos, es posible conocer:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Qu\u00e9 datos se consideran sensibles en el contexto de pagos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Cu\u00e1les son las pr\u00e1cticas seguras para prevenir fraudes, accesos no autorizados y filtraciones de datos financieros.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Estas son solo algunas de las normativas que gu\u00edan nuestro compromiso con la seguridad de la informaci\u00f3n, la privacidad de los datos y la resiliencia operativa. Pero el camino no termina aqu\u00ed, seguimos trabajando activamente para incorporar y cumplir con nuevos marcos regulatorios.<\/span><\/p>\n<h3><b>\u00bfC\u00f3mo te ayudamos<\/b> <b>con el cumplimiento de normativas?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Uno de los grandes diferenciales de SMARTFENSE es su <\/span><b>Componente de Gesti\u00f3n de Normativas<\/b><span style=\"font-weight: 400;\">, que permite:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Mapear los contenidos formativos con cl\u00e1usulas espec\u00edficas<\/b><span style=\"font-weight: 400;\"> de cada normativa.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Demostrar cumplimiento<\/b><span style=\"font-weight: 400;\"> con reportes detallados.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Realizar un seguimiento<\/b><span style=\"font-weight: 400;\"> claro del avance en campa\u00f1as de concientizaci\u00f3n.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Esta trazabilidad convierte a la formaci\u00f3n en un elemento central del sistema de cumplimiento normativo.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-26475\" src=\"https:\/\/smartfense.com\/file\/2024\/08\/Contenidos-de-normativa.png\" alt=\"contenidos que cumplen la normativa\" width=\"1200\" height=\"630\" srcset=\"https:\/\/smartfense.com\/file\/2024\/08\/Contenidos-de-normativa.png 1200w, https:\/\/smartfense.com\/file\/2024\/08\/Contenidos-de-normativa-300x158.png 300w, https:\/\/smartfense.com\/file\/2024\/08\/Contenidos-de-normativa-1024x538.png 1024w, https:\/\/smartfense.com\/file\/2024\/08\/Contenidos-de-normativa-768x403.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>\u00a0<\/p>\n<h3><b>Cuando la clave est\u00e1 en concientizar a las personas<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">La protecci\u00f3n de datos y la ciberseguridad ya no pueden tratarse como temas aislados o exclusivamente t\u00e9cnicos. Las normativas actuales lo dejan claro: <\/span><b>es imprescindible involucrar a las personas<\/b><span style=\"font-weight: 400;\">, y para eso, la concientizaci\u00f3n es una herramienta fundamental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contar con una plataforma como SMARTFENSE permite no solo <\/span><b>reducir riesgos<\/b><span style=\"font-weight: 400;\">, sino tambi\u00e9n <\/span><b>cumplir con los requisitos regulatorios <\/b><span style=\"font-weight: 400;\">de forma medible y alineada con los marcos m\u00e1s exigentes.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-38577\" src=\"https:\/\/smartfense.com\/file\/2025\/08\/ES-AR.png\" alt=\"Infografia legislacion\" width=\"1300\" height=\"3250\" srcset=\"https:\/\/smartfense.com\/file\/2025\/08\/ES-AR.png 1300w, https:\/\/smartfense.com\/file\/2025\/08\/ES-AR-120x300.png 120w, https:\/\/smartfense.com\/file\/2025\/08\/ES-AR-410x1024.png 410w, https:\/\/smartfense.com\/file\/2025\/08\/ES-AR-768x1920.png 768w, https:\/\/smartfense.com\/file\/2025\/08\/ES-AR-614x1536.png 614w, https:\/\/smartfense.com\/file\/2025\/08\/ES-AR-819x2048.png 819w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<p><em>Fuente: SMARTFENSE<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones, independientemente del sector al que pertenezcan, est\u00e1n expuestas [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":38491,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[198],"tags":[241,236,1347,2003,922,1350,2004,1450,2005,2006],"class_list":["post-38556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-ciberseguridad-es-ar","tag-concientizacion","tag-cumplimiento-de-normativas-es-ar","tag-dora-es-ar","tag-europa-es-ar","tag-gdpr-es-ar","tag-leyes-es-ar","tag-nis2-es-ar","tag-pci-dss-es-ar","tag-ue-es-ar"],"acf":[],"yoast_head":" \n<title>Cumplimiento normativo: un compromiso sostenido con la ciberseguridad - SMARTFENSE<\/title>\n<meta name=\"description\" content=\"ciberseguridad, concientizaci\u00f3n, Cumplimiento de Normativas, Dora, europa, GDPR, leyes, nis2, PCI DSS, UE - En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad - SMARTFENSE\" \/>\n<meta property=\"og:description\" content=\"ciberseguridad, concientizaci\u00f3n, Cumplimiento de Normativas, Dora, europa, GDPR, leyes, nis2, PCI DSS, UE - En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"SMARTFENSE\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-22T10:05:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-26T09:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ver\u00f3nica Voisin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ver\u00f3nica Voisin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/\"},\"author\":{\"name\":\"Ver\u00f3nica Voisin\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/person\\\/90dd6dc697f20b0bb459ed03fc2722d7\"},\"headline\":\"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad\",\"datePublished\":\"2025-08-22T10:05:19+00:00\",\"dateModified\":\"2025-08-26T09:36:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/\"},\"wordCount\":854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Sin-titulo-12.jpg\",\"keywords\":[\"ciberseguridad\",\"concientizaci\u00f3n\",\"Cumplimiento de Normativas\",\"Dora\",\"europa\",\"GDPR\",\"leyes\",\"nis2\",\"PCI DSS\",\"UE\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/\",\"name\":\"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad - SMARTFENSE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Sin-titulo-12.jpg\",\"datePublished\":\"2025-08-22T10:05:19+00:00\",\"dateModified\":\"2025-08-26T09:36:27+00:00\",\"description\":\"ciberseguridad, concientizaci\u00f3n, Cumplimiento de Normativas, Dora, europa, GDPR, leyes, nis2, PCI DSS, UE - En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Sin-titulo-12.jpg\",\"contentUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Sin-titulo-12.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Leyes ciberseguridad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/blog\\\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/concientizacion-en-ciberseguridad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#website\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/\",\"name\":\"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\",\"name\":\"SMARTFENSE\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"contentUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"width\":241,\"height\":40,\"caption\":\"SMARTFENSE\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/person\\\/90dd6dc697f20b0bb459ed03fc2722d7\",\"name\":\"Ver\u00f3nica Voisin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9feea25a1a08bf83e7b320ec255bc5c489589971d89f49a2a0418284def92d5a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9feea25a1a08bf83e7b320ec255bc5c489589971d89f49a2a0418284def92d5a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9feea25a1a08bf83e7b320ec255bc5c489589971d89f49a2a0418284def92d5a?s=96&d=mm&r=g\",\"caption\":\"Ver\u00f3nica Voisin\"},\"description\":\"Profesional con amplia experiencia en el desarrollo de contenidos de ciberseguridad, tecnolog\u00eda de la informaci\u00f3n y concienciaci\u00f3n en seguridad. Desarrolla y gestiona contenidos educativos y creativos enfocados a audiencias heterog\u00e9neas.\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/author\\\/veronica\\\/\"}]}<\/script>\n ","yoast_head_json":{"title":"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad - SMARTFENSE","description":"ciberseguridad, concientizaci\u00f3n, Cumplimiento de Normativas, Dora, europa, GDPR, leyes, nis2, PCI DSS, UE - En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/","og_locale":"es_ES","og_type":"article","og_title":"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad - SMARTFENSE","og_description":"ciberseguridad, concientizaci\u00f3n, Cumplimiento de Normativas, Dora, europa, GDPR, leyes, nis2, PCI DSS, UE - En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones,","og_url":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/","og_site_name":"SMARTFENSE","article_published_time":"2025-08-22T10:05:19+00:00","article_modified_time":"2025-08-26T09:36:27+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-12.jpg","type":"image\/jpeg"}],"author":"Ver\u00f3nica Voisin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ver\u00f3nica Voisin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#article","isPartOf":{"@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/"},"author":{"name":"Ver\u00f3nica Voisin","@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/person\/90dd6dc697f20b0bb459ed03fc2722d7"},"headline":"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad","datePublished":"2025-08-22T10:05:19+00:00","dateModified":"2025-08-26T09:36:27+00:00","mainEntityOfPage":{"@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/"},"wordCount":854,"commentCount":0,"publisher":{"@id":"https:\/\/smartfense.com\/es-ar\/#organization"},"image":{"@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-12.jpg","keywords":["ciberseguridad","concientizaci\u00f3n","Cumplimiento de Normativas","Dora","europa","GDPR","leyes","nis2","PCI DSS","UE"],"articleSection":["Blog"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/","url":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/","name":"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad - SMARTFENSE","isPartOf":{"@id":"https:\/\/smartfense.com\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#primaryimage"},"image":{"@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-12.jpg","datePublished":"2025-08-22T10:05:19+00:00","dateModified":"2025-08-26T09:36:27+00:00","description":"ciberseguridad, concientizaci\u00f3n, Cumplimiento de Normativas, Dora, europa, GDPR, leyes, nis2, PCI DSS, UE - En el contexto actual, hablar de cumplimiento normativo ya no es una cuesti\u00f3n exclusiva del \u00e1rea legal o de compliance. Las organizaciones,","breadcrumb":{"@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#primaryimage","url":"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-12.jpg","contentUrl":"https:\/\/smartfense.com\/file\/2025\/08\/Sin-titulo-12.jpg","width":1920,"height":1280,"caption":"Leyes ciberseguridad"},{"@type":"BreadcrumbList","@id":"https:\/\/smartfense.com\/es-ar\/blog\/cumplimiento-normativo-un-compromiso-sostenido-con-la-ciberseguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/smartfense.com\/es-ar\/concientizacion-en-ciberseguridad\/"},{"@type":"ListItem","position":2,"name":"Cumplimiento normativo: un compromiso sostenido con la ciberseguridad"}]},{"@type":"WebSite","@id":"https:\/\/smartfense.com\/es-ar\/#website","url":"https:\/\/smartfense.com\/es-ar\/","name":"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad","description":"","publisher":{"@id":"https:\/\/smartfense.com\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartfense.com\/es-ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/smartfense.com\/es-ar\/#organization","name":"SMARTFENSE","url":"https:\/\/smartfense.com\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","contentUrl":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","width":241,"height":40,"caption":"SMARTFENSE"},"image":{"@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/person\/90dd6dc697f20b0bb459ed03fc2722d7","name":"Ver\u00f3nica Voisin","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/9feea25a1a08bf83e7b320ec255bc5c489589971d89f49a2a0418284def92d5a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9feea25a1a08bf83e7b320ec255bc5c489589971d89f49a2a0418284def92d5a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9feea25a1a08bf83e7b320ec255bc5c489589971d89f49a2a0418284def92d5a?s=96&d=mm&r=g","caption":"Ver\u00f3nica Voisin"},"description":"Profesional con amplia experiencia en el desarrollo de contenidos de ciberseguridad, tecnolog\u00eda de la informaci\u00f3n y concienciaci\u00f3n en seguridad. Desarrolla y gestiona contenidos educativos y creativos enfocados a audiencias heterog\u00e9neas.","url":"https:\/\/smartfense.com\/es-ar\/author\/veronica\/"}]}},"_links":{"self":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts\/38556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/comments?post=38556"}],"version-history":[{"count":4,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts\/38556\/revisions"}],"predecessor-version":[{"id":38594,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts\/38556\/revisions\/38594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/media\/38491"}],"wp:attachment":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/media?parent=38556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/categories?post=38556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/tags?post=38556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}