{"id":31702,"date":"2023-07-07T15:11:08","date_gmt":"2023-07-07T15:11:08","guid":{"rendered":"https:\/\/smartfense.com\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concienciacion-son-legales\/"},"modified":"2024-11-13T11:18:21","modified_gmt":"2024-11-13T10:18:21","slug":"perfiles-psicologicos-en-plataformas-de-concientizacion","status":"publish","type":"post","link":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/","title":{"rendered":"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales?"},"content":{"rendered":"<p>En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de concientizaci\u00f3n.<\/p>\n<p>La idea es la siguiente:\u00a0<strong>determinar el perfil psicol\u00f3gico de nuestros usuarios<\/strong> a trav\u00e9s de diferentes t\u00e9cnicas y algoritmos y con esta informaci\u00f3n entregar contenidos de concientizaci\u00f3n adaptados a las necesidades de cada persona. Adem\u00e1s, realizar simulaciones de phishing espec\u00edficas para explotar las debilidades de cada perfil.<\/p>\n<p><em>Un perfil psicol\u00f3gico puede determinarse de manera sencilla mediante el uso de encuestas, o tambi\u00e9n puede llevarse a cabo de una manera un poco menos transparente mediante el uso de chatbots o inteligencia artificial.<\/em><\/p>\n<p>M\u00e1s all\u00e1 de que el uso de estos perfiles en concientizaci\u00f3n es un m\u00e9todo del cual no se encuentra evidencia suficiente que acredite su efectividad, hay algo todav\u00eda m\u00e1s importante: <strong>El perfil psicol\u00f3gico de una persona es informaci\u00f3n cl\u00ednica.<\/strong><\/p>\n<p>Por este motivo, si planeamos realizar tests psicol\u00f3gicos de nuestros usuarios, almacenar esta informaci\u00f3n y tomar decisiones al respecto,\u00a0<strong>tenemos que tener much\u00edsimo cuidado<\/strong>.<\/p>\n<p>Veamos lo que implica esto en el marco del GDPR:<\/p>\n<h3><strong>Acceso a la informaci\u00f3n<\/strong><\/h3>\n<p>Una plataforma de concientizaci\u00f3n normalmente puede ser accedida por:<\/p>\n<ul>\n<li aria-level=\"1\">El\u00a0<strong>responsable de seguridad o de tecnolog\u00eda<\/strong>\u00a0de nuestra organizaci\u00f3n.<\/li>\n<li aria-level=\"1\">Los\u00a0<strong>analistas o el equipo<\/strong> responsable de administrar el plan de concientizaci\u00f3n de nuestra organizaci\u00f3n.<\/li>\n<li aria-level=\"1\">El\u00a0<strong>personal del partner<\/strong> que brinda el servicio gestionado de concientizaci\u00f3n.<\/li>\n<\/ul>\n<p>Si la plataforma contiene informaci\u00f3n sobre el perfil psicol\u00f3gico de nuestros usuarios\u00a0entonces nos encontramos en una situaci\u00f3n realmente delicada. Este tipo de informaci\u00f3n sensible es normalmente restringida a personal especializado en psicolog\u00eda que tiene un rol definido dentro de la organizaci\u00f3n y gestiona esta informaci\u00f3n con m\u00e1ximo secreto. \u00danicamente estas personas deber\u00edan poder ver informaci\u00f3n, reportes o cualquier dato relacionado con los perfiles psicol\u00f3gicos de los usuarios.<\/p>\n<h3><strong>Transparencia<\/strong><\/h3>\n<p>Los usuarios de nuestra organizaci\u00f3n\u00a0<strong>deben comprender c\u00f3mo se van a elaborar sus perfiles psicol\u00f3gicos<\/strong>.<\/p>\n<p>Aqu\u00ed puede que nos enfrentemos a diversos desaf\u00edos. Si estamos utilizando por ejemplo una encuesta, podremos explicarlo de manera clara y sencilla. Si nuestra plataforma de concientizaci\u00f3n elabora los perfiles mediante algoritmos o herramientas de IA es realmente muy dif\u00edcil que podamos conocer los pormenores de este proceso <strong>y mucho m\u00e1s dif\u00edcil a\u00fan que podamos transmitir de manera clara este proceso<\/strong>\u00a0para que todas las personas de nuestra organizaci\u00f3n lo comprendan.<\/p>\n<p>Esto es relevante ya que esta comprensi\u00f3n es la que luego\u00a0<strong>permite a las personas ejercer sus derechos de privacidad<\/strong>\u00a0y tambi\u00e9n la base del siguiente punto.<\/p>\n<h3><strong>Consentimiento<\/strong><\/h3>\n<p>Si vamos a manejar informaci\u00f3n relacionada con la salud de nuestros usuarios, entonces tenemos que tener su consentimiento. Esto implica que los usuarios comprendan\u00a0<strong>por qu\u00e9\u00a0<\/strong>vamos a determinar y almacenar esta informaci\u00f3n,\u00a0<strong>c\u00f3mo<\/strong>\u00a0la vamos a utilizar y\u00a0<strong>qu\u00e9<\/strong>\u00a0puede implicar para ellos en cuestiones de privacidad. Este consentimiento tiene a su vez que ser claramente demostrable y trazable.<\/p>\n<h3><strong>Discriminaci\u00f3n y sesgos<\/strong><\/h3>\n<p>Si vamos a utilizar los perfiles psicol\u00f3gicos para agrupar a nuestros usuarios y tomar decisiones al respecto (como enviar cierta trampa de simulaci\u00f3n de phishing o adaptar cierto mensaje de concientizaci\u00f3n) debemos tener en cuenta lo siguiente: Estamos recurriendo a una pr\u00e1ctica que es<strong>\u00a0cuestionable desde el punto de vista \u00e9tico<\/strong>.<\/p>\n<p>Los tests psicol\u00f3gicos pueden estar basados en patrones que reflejen prejuicios o estereotipos que nos lleven a\u00a0<strong>tomar decisiones injustas o discriminatorias<\/strong>.<\/p>\n<h2><strong>Conclusi\u00f3n<\/strong><\/h2>\n<p>Si vamos a elaborar, almacenar y utilizar los perfiles psicol\u00f3gicos de nuestros usuarios en nuestro programa de concientizaci\u00f3n debemos tener realmente mucho cuidado ya que podemos cometer una <strong>violaci\u00f3n grave de privacidad.<\/strong><\/p>\n<p>Los datos cl\u00ednicos son altamente confidenciales. Si no se implementan las medidas adecuadas para proteger la privacidad de nuestros usuarios, existe el riesgo de violar sus derechos fundamentales a la privacidad y la protecci\u00f3n de datos.<\/p>\n<p>Dicho esto y llegados a esta etapa del art\u00edculo, es momento de apelar a nuestro propio juicio como responsables de ciberseguridad:\u00a0<strong>\u00bfrealmente es relevante el perfil psicol\u00f3gico de nuestros usuarios para cumplir los objetivos de nuestro programa de concientizaci\u00f3n? <\/strong>\u00bfExiste evidencia que respalde el uso de este m\u00e9todo para el desarrollo de una cultura segura? \u00bfContamos con las herramientas y asesoramiento legal necesario para que nuestro programa sea considerado legal y cumpla con un reglamento tan relevante como el GDPR?<\/p>\n<p>Conceptos tan renombrados como el Due Diligence y el Due Care cobran gran relevancia cuando evaluamos las respuestas a estas preguntas. Esperamos que sean \u00fatiles y permitan tomar decisiones profesionales e informadas sobre los programas de concientizaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<h2><strong>Fuente<\/strong><\/h2>\n<p>El presente art\u00edculo se basa en el an\u00e1lisis realizado por el abogado Marcelo Temperini, especialista en Derecho Inform\u00e1tico, Privacidad y Cibercrimen, en su art\u00edculo:\u00a0<a href=\"https:\/\/www.linkedin.com\/pulse\/los-peligros-de-test-psicol%2525C3%2525B3gicos-en-la-prevenci%2525C3%2525B3n-fraude-temperini%3FtrackingId=NOQEHRHwSdiFJMQkYi5O5A%253D%253D\/?trackingId=NOQEHRHwSdiFJMQkYi5O5A%3D%3D\" target=\"_blank\" rel=\"noopener\">Los peligros de los tests psicol\u00f3gicos en la prevenci\u00f3n de fraude y el cumplimiento del GDPR<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de concientizaci\u00f3n. La idea es la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[223,835,241,236,1248],"class_list":["post-31702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-cambio-de-comportamiento-es-ar","tag-ciberamenazas-es-ar","tag-ciberseguridad-es-ar","tag-concientizacion","tag-psicologia"],"acf":[],"yoast_head":" \n<title>Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales? - SMARTFENSE<\/title>\n<meta name=\"description\" content=\"cambio de comportamiento, ciberamenazas, ciberseguridad, concientizaci\u00f3n, psicologia - En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales? - SMARTFENSE\" \/>\n<meta property=\"og:description\" content=\"cambio de comportamiento, ciberamenazas, ciberseguridad, concientizaci\u00f3n, psicologia - En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/\" \/>\n<meta property=\"og:site_name\" content=\"SMARTFENSE\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-07T15:11:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T10:18:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smartfense.com\/file\/2023\/08\/dinero_euros_ley.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicol\u00e1s Bruna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00e1s Bruna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/\"},\"author\":{\"name\":\"Nicol\u00e1s Bruna\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/person\\\/5494c12e79213c554fa449135589c24c\"},\"headline\":\"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales?\",\"datePublished\":\"2023-07-07T15:11:08+00:00\",\"dateModified\":\"2024-11-13T10:18:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/\"},\"wordCount\":865,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/dinero_euros_ley.jpg\",\"keywords\":[\"cambio de comportamiento\",\"ciberamenazas\",\"ciberseguridad\",\"concientizaci\u00f3n\",\"psicologia\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/\",\"name\":\"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales? - SMARTFENSE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/dinero_euros_ley.jpg\",\"datePublished\":\"2023-07-07T15:11:08+00:00\",\"dateModified\":\"2024-11-13T10:18:21+00:00\",\"description\":\"cambio de comportamiento, ciberamenazas, ciberseguridad, concientizaci\u00f3n, psicologia - En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/dinero_euros_ley.jpg\",\"contentUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/dinero_euros_ley.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/sin-categorizar\\\/perfiles-psicologicos-en-plataformas-de-concientizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/concientizacion-en-ciberseguridad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#website\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/\",\"name\":\"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#organization\",\"name\":\"SMARTFENSE\",\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"contentUrl\":\"https:\\\/\\\/smartfense.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-smartfense-240x40-1.png\",\"width\":241,\"height\":40,\"caption\":\"SMARTFENSE\"},\"image\":{\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/#\\\/schema\\\/person\\\/5494c12e79213c554fa449135589c24c\",\"name\":\"Nicol\u00e1s Bruna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b03096bf4c3dd886cfcffd7415eadf6f80d2c8126188409e7d4d1d1b6b911fcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b03096bf4c3dd886cfcffd7415eadf6f80d2c8126188409e7d4d1d1b6b911fcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b03096bf4c3dd886cfcffd7415eadf6f80d2c8126188409e7d4d1d1b6b911fcb?s=96&d=mm&r=g\",\"caption\":\"Nicol\u00e1s Bruna\"},\"description\":\"Product Manager de SMARTFENSE. Su misi\u00f3n en la empresa es mejorar la plataforma d\u00eda a d\u00eda y evangelizar sobre la importancia de la concientizaci\u00f3n. Ha escrito dos whitepapers y m\u00e1s de 150 art\u00edculos sobre gesti\u00f3n del riesgo de la ingenier\u00eda social, creaci\u00f3n de culturas seguras y cumplimiento de normativas. Tambi\u00e9n es uno de los autores de la Gu\u00eda de Ransomware de OWASP y el Calculador de costos de Ransomware, entre otros recursos gratuitos.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nicolasbruna\\\/\"],\"url\":\"https:\\\/\\\/smartfense.com\\\/es-ar\\\/author\\\/nicolas\\\/\"}]}<\/script>\n ","yoast_head_json":{"title":"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales? - SMARTFENSE","description":"cambio de comportamiento, ciberamenazas, ciberseguridad, concientizaci\u00f3n, psicologia - En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/","og_locale":"es_ES","og_type":"article","og_title":"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales? - SMARTFENSE","og_description":"cambio de comportamiento, ciberamenazas, ciberseguridad, concientizaci\u00f3n, psicologia - En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de","og_url":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/","og_site_name":"SMARTFENSE","article_published_time":"2023-07-07T15:11:08+00:00","article_modified_time":"2024-11-13T10:18:21+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/smartfense.com\/file\/2023\/08\/dinero_euros_ley.jpg","type":"image\/jpeg"}],"author":"Nicol\u00e1s Bruna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nicol\u00e1s Bruna","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#article","isPartOf":{"@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/"},"author":{"name":"Nicol\u00e1s Bruna","@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/person\/5494c12e79213c554fa449135589c24c"},"headline":"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales?","datePublished":"2023-07-07T15:11:08+00:00","dateModified":"2024-11-13T10:18:21+00:00","mainEntityOfPage":{"@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/"},"wordCount":865,"commentCount":0,"publisher":{"@id":"https:\/\/smartfense.com\/es-ar\/#organization"},"image":{"@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/smartfense.com\/file\/2023\/08\/dinero_euros_ley.jpg","keywords":["cambio de comportamiento","ciberamenazas","ciberseguridad","concientizaci\u00f3n","psicologia"],"articleSection":["Sin categorizar"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/","url":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/","name":"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales? - SMARTFENSE","isPartOf":{"@id":"https:\/\/smartfense.com\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#primaryimage"},"image":{"@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/smartfense.com\/file\/2023\/08\/dinero_euros_ley.jpg","datePublished":"2023-07-07T15:11:08+00:00","dateModified":"2024-11-13T10:18:21+00:00","description":"cambio de comportamiento, ciberamenazas, ciberseguridad, concientizaci\u00f3n, psicologia - En los \u00faltimos a\u00f1os me he encontrado con algunas consultas acerca del uso de perfiles psicol\u00f3gicos como herramienta para guiar las decisiones del plan de","breadcrumb":{"@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#primaryimage","url":"https:\/\/smartfense.com\/file\/2023\/08\/dinero_euros_ley.jpg","contentUrl":"https:\/\/smartfense.com\/file\/2023\/08\/dinero_euros_ley.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/smartfense.com\/es-ar\/sin-categorizar\/perfiles-psicologicos-en-plataformas-de-concientizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/smartfense.com\/es-ar\/concientizacion-en-ciberseguridad\/"},{"@type":"ListItem","position":2,"name":"Perfiles psicol\u00f3gicos en plataformas de concientizaci\u00f3n, \u00bfson legales?"}]},{"@type":"WebSite","@id":"https:\/\/smartfense.com\/es-ar\/#website","url":"https:\/\/smartfense.com\/es-ar\/","name":"SMARTFENSE - Concienciaci\u00f3n en Ciberseguridad","description":"","publisher":{"@id":"https:\/\/smartfense.com\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smartfense.com\/es-ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/smartfense.com\/es-ar\/#organization","name":"SMARTFENSE","url":"https:\/\/smartfense.com\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","contentUrl":"https:\/\/smartfense.com\/file\/2023\/08\/logo-smartfense-240x40-1.png","width":241,"height":40,"caption":"SMARTFENSE"},"image":{"@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/smartfense.com\/es-ar\/#\/schema\/person\/5494c12e79213c554fa449135589c24c","name":"Nicol\u00e1s Bruna","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/b03096bf4c3dd886cfcffd7415eadf6f80d2c8126188409e7d4d1d1b6b911fcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b03096bf4c3dd886cfcffd7415eadf6f80d2c8126188409e7d4d1d1b6b911fcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b03096bf4c3dd886cfcffd7415eadf6f80d2c8126188409e7d4d1d1b6b911fcb?s=96&d=mm&r=g","caption":"Nicol\u00e1s Bruna"},"description":"Product Manager de SMARTFENSE. Su misi\u00f3n en la empresa es mejorar la plataforma d\u00eda a d\u00eda y evangelizar sobre la importancia de la concientizaci\u00f3n. Ha escrito dos whitepapers y m\u00e1s de 150 art\u00edculos sobre gesti\u00f3n del riesgo de la ingenier\u00eda social, creaci\u00f3n de culturas seguras y cumplimiento de normativas. Tambi\u00e9n es uno de los autores de la Gu\u00eda de Ransomware de OWASP y el Calculador de costos de Ransomware, entre otros recursos gratuitos.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolasbruna\/"],"url":"https:\/\/smartfense.com\/es-ar\/author\/nicolas\/"}]}},"_links":{"self":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts\/31702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/comments?post=31702"}],"version-history":[{"count":2,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts\/31702\/revisions"}],"predecessor-version":[{"id":31705,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/posts\/31702\/revisions\/31705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/media\/11756"}],"wp:attachment":[{"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/media?parent=31702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/categories?post=31702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartfense.com\/es-ar\/wp-json\/wp\/v2\/tags?post=31702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}